{"id":359,"count":4,"description":"<p data-start=\"158\" data-end=\"461\">Las <strong data-start=\"162\" data-end=\"202\">excursiones de medio d\u00eda de \u00c1loratur<\/strong> est\u00e1n pensadas para quienes quieren exprimir su visita a M\u00e1laga sin renunciar a la comodidad. Disfruta rutas guiadas por el entorno del <strong data-start=\"339\" data-end=\"394\">Caminito del Rey, \u00c1lora y otros pueblos con encanto<\/strong>, con transporte organizado, horarios c\u00f3modos y grupos reducidos.<\/p>\r\n<p data-start=\"469\" data-end=\"756\">Nuestros gu\u00edas especializados te acompa\u00f1an para que descubras la <strong data-start=\"534\" data-end=\"603\">historia, la cultura y los paisajes m\u00e1s espectaculares de la zona<\/strong>, en una experiencia segura, cercana y bien planificada. Elige tu excursi\u00f3n de medio d\u00eda ideal y convi\u00e9rtela en uno de los mejores recuerdos de tu viaje.<\/p>\r\n<p data-start=\"469\" data-end=\"756\"><a href=\"https:\/\/aloratur.com\/wp-content\/uploads\/2025\/09\/camintodelrey-1-1.webp\"><img class=\"alignnone size-medium wp-image-17838\" src=\"https:\/\/aloratur.com\/wp-content\/uploads\/2025\/09\/camintodelrey-1-1-300x184.webp\" alt=\"\" width=\"300\" height=\"184\" \/><\/a><\/p>","link":"https:\/\/aloratur.com\/fr\/seccion\/excursiones\/excursiones-de-medio-dia\/","name":"Excursions d'une demi-journ\u00e9e","slug":"excursiones-de-medio-dia","taxonomy":"category","parent":360,"meta":[],"_links":{"self":[{"href":"https:\/\/aloratur.com\/fr\/wp-json\/wp\/v2\/categories\/359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aloratur.com\/fr\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/aloratur.com\/fr\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/aloratur.com\/fr\/wp-json\/wp\/v2\/categories\/360"}],"wp:post_type":[{"href":"https:\/\/aloratur.com\/fr\/wp-json\/wp\/v2\/posts?categories=359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}